{"id":91,"date":"2019-05-04T20:46:01","date_gmt":"2019-05-04T18:46:01","guid":{"rendered":"http:\/\/www.minpx.com\/?p=91"},"modified":"2024-05-03T16:41:50","modified_gmt":"2024-05-03T14:41:50","slug":"ein-ruckblick-und-ein-uberblick-uber-meine-arbeitsmittel","status":"publish","type":"post","link":"http:\/\/www.minpx.com\/index.php\/2019\/05\/04\/ein-ruckblick-und-ein-uberblick-uber-meine-arbeitsmittel\/","title":{"rendered":"Ein R\u00fcckblick und ein \u00dcberblick \u00fcber meine Arbeitsmittel"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Bevor ich Beitr\u00e4ge des alten Servers wiederherstelle m\u00f6chte ich einen kleinen R\u00fcckblick meines Werdegangs geben und warum ich benutze was ich benutze. Ich m\u00f6chte hier nur einen Teil meiner Entwicklung als Fotograf beleuchten, jenen der f\u00fcr diesen Blog relevant ist. Der Bereich Mode- und Architekturfotografie, der den Gro\u00dfteil meiner Laufbahn bestimmt hat, geh\u00f6rt hier nicht dazu. Hier m\u00f6chte ich den Bogen spannen, was die Leidenschaft f\u00fcr die Fotografie begr\u00fcndet hat und zu der ich seit einigen Jahren zur\u00fcckgekehrt bin.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Dazu muss ich ein wenig ausholen da sich im Lauf der Zeit vieles aus einer Notwendigkeit bzw. aus einem (eingebildeten) Bedarf ergeben hat. Bereits als Kind, ich war denke ich 6 oder 7 \u2013 mitten in den 1970ern, bekam ich zuf\u00e4llig eine \u201eKamera\u201c in die Hand, eine Spielzeugkamera komplett aus Plastik und einem einfachen Plastikobjektiv, mit dem ich begeistert eine Filmrolle knipste. Ich kann mich noch gut erinnern wie ich meine Mutter mehrfach gefragt hatte wie ich denn da jetzt die Bilder sehen kann. Widerwillig, da das ein teures Vergn\u00fcgen war, gab meine Mutter dann den Film zur Ausarbeitung, nicht ohne den Hinweis loswerden zu m\u00fcssen, das w\u00e4re vermutlich nur unbrauchbarer Ausschuss. Ich wei\u00df nicht wo die Bilder geblieben sind aber ich habe den \u00fcberraschten Aufschrei meiner Mutter, dass die Bilder richtig gut w\u00e4ren noch im Ohr. Vielleicht wollte sie mir aber auch nur ein gutes Gef\u00fchl geben. Das war jedenfalls f\u00fcr l\u00e4ngere Zeit meine einzige Ber\u00fchrung mit Fotografie.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Mein Elternhaus hat mir alles erm\u00f6glicht, nur Ausfl\u00fcge in k\u00fcnstlerische Gefilde wurden als nutzlos abgetan und wenig unterst\u00fctzt. T\u00e4tigkeiten wie fotografieren war etwas f\u00fcr die Freizeit, Ausfl\u00fcge oder Urlaub aber nicht als tats\u00e4chliche Besch\u00e4ftigung. Ich wurde daher im Bereich Fotografie nicht besonders gef\u00f6rdert, vermutlich weil ich keine besondere Sache daraus machen wollte \u2013 der Wunsch nach k\u00fcnstlerischer Entfaltung, sowohl in der Malerei, Grafik oder auch Fotografie war immer vorhanden und Teil meines Lebens.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Als ich als Jugendlicher, ich war 15 oder 16 Jahre alt, meine erste eigene Kamera gekauft habe, war das keine Digitalkamera im heutigen Sinne, es gab etwas Elektronik und Autofokus aber es war im Grunde eine analoge Kamera, eine Minolta 5000. Als Sch\u00fcler, mit meinen bescheidenen finanziellen M\u00f6glichkeiten, blieb mir nichts anderes \u00fcbrig als mit einer g\u00fcnstigen Kamera zu \u201earbeiten\u201c. Mit dieser ersten Kamera habe ich viele Bilder gemacht, wobei ich mir die Ausarbeitung im Labor nicht leisten konnte, so habe ich mich auf Dia-Fotografie beschr\u00e4nkt. Nur im Urlaub und auf Reisen habe ich ASA100 Filmrollen verwendet \u2013 denn das wurde von den Eltern gesponsert. Als (Kit)Objektiv gab es ein 35-80mm \u01921:4-5.6 und ich habe mich damals richtig gefreut damit Dias und Fotos zu machen, ich war mit Kamera und Bildern zufrieden \u2013 etwas das ich heute nicht mehr ganz nachvollziehen kann. Mit dem Objektiv auch nur ein halbwegs scharfes Bild zu machen grenzt an ein Wunder. Die Kamera habe ich noch und Testfotografien damit waren ern\u00fcchternd. Als ich nach bald 30 Jahren die Kamera zuletzt in der Hand hatte, musste ich mit einem Grinsen festellen, die Objektiveinstellung stand unver\u00e4ndert nicht auf AF, sondern auf M. Technisch war ich trotzdem v\u00f6llig unbedarft, das Einzige was ich damals mit Akribie versucht hatte war einem fotografischen Blick nachzueifern, obwohl mir Begriffe wie Bokeh, Tiefensch\u00e4rfe, goldener Schnitt etc unbekannt waren. Zumindest bis ich mein erstes Fotobuch geschenkt bekam, die Canon Fotoschule und ich hatte das Buch beinahe auswendig gelernt. Um ehrlich zu sein, ich hatte nicht alles verstanden was dort erkl\u00e4rt wurde aber das war mir nicht so wichtig, es hatte mich inspiriert besser werden zu wollen.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p>Ob analoge oder digitale Fotografie, beides hat seine Eigenheiten und auch seine Vorz\u00fcge. Heute bin ich bequem und nutze (fast) ausschlie\u00dflich digitales Equipment aber ich fotografiere ausschlie\u00dflich mit manuellen Einstellungen und nutze zB Autofokus nur mit ganz spezifischen \u00fcber lange Zeit entwickelten Settings, die zur jeweiligen Fototour passt. Ich habe Ausl\u00f6ser und Fokussierung auch bewusst getrennt, denn ich m\u00f6chte es (aus alter Schule) selbst in der Hand haben was, wann fokussiert wird. Beim Birding nutze ich niemals Autofokus, er ist (mir) bis heute zu unzuverl\u00e4ssig.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte darauf hinweisen, dass das eigene Wirken, die eigenen Interessen und die eigenen Erfahrungen daf\u00fcr verantwortlich sein m\u00fcssen, welche Ausr\u00fcstung man braucht und anschafft. Ich hatte niemals den Wunsch ein Foto wie &#8230; zu machen und dann alles gekauft womit ein bestimmtes Bild gemacht wurde. Erstens m\u00f6chte ich nicht die finanziellen Mittel f\u00fcr eine Kopie aufwenden und zweitens w\u00e4re es auch dann nicht sicher ob ich damit auch nur ansatzweise solche Bilder machen kann oder will.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">F\u00fcr mich braucht es den Anreiz aus der eigenen Erfahrung und da ist in den letzten Jahrzehnten und Jahren eine (f\u00fcr mich) ganz brauchbare Ausstattung zusammen gekommen.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Mein haupts\u00e4chliches Arbeitswerkzeug heute ist eine Canon 5D Mark IV, alternativ eine 5D Mark III und eine 7D Mark II. Die Objektive aufzuz\u00e4hlen w\u00fcrde den Rahmen sprengen, weil ich unterschiedliche Objektive f\u00fcr unterschiedliche Eins\u00e4tze habe. Dabei decke ich alles mit einer guten Auswahl von Zoom- und Festbrennweiten von 11mm bis 800mm ab.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Superweitwinkel und Weitwinkel, sowie Tilt-Shift bevorzuge ich bei Architektur- und Landschaftsaufnahmen, Festbrennweiten haupts\u00e4chlich bei Portraits auf Reisen oder bei Lust und Laune (street-Art) und Teleobjektive sind vor allem bei Birdfotografie im Einsatz. Je nach Objektiv und Kamera und Einsatzzweck gibt es auch unterschiedliche Stative, vom Heavy Duty mit gro\u00dfem Gimbal bis hin zum kleinen leichten Reisestativ mit diversen Kugelk\u00f6pfen unterschiedlicher Gewichtsklassen.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Vielleicht wenn es sich ergibt, werde ich in Beitr\u00e4gen erl\u00e4utern was mich dazu bewegt hat bestimmte Teile zu holen. Auch wird es nat\u00fcrlich Beitr\u00e4ge geben um meine Kameraeinstellungen zu erkl\u00e4ren und letztendlich auch die Post-Production streifen.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Bevor ich Beitr\u00e4ge des alten Servers wiederherstelle m\u00f6chte ich einen kleinen R\u00fcckblick meines Werdegangs geben und warum ich benutze was ich benutze. Ich m\u00f6chte hier nur einen Teil meiner Entwicklung als Fotograf beleuchten, jenen der f\u00fcr diesen Blog relevant ist. Der Bereich Mode- und Architekturfotografie, der den Gro\u00dfteil meiner Laufbahn&hellip; <\/p>\n","protected":false},"author":1,"featured_media":92,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-91","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausruestung"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.minpx.com\/wp-content\/uploads\/2019\/05\/equipement.jpg?fit=2048%2C1365","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/posts\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":10,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/posts\/91\/revisions"}],"predecessor-version":[{"id":1033,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/posts\/91\/revisions\/1033"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/media\/92"}],"wp:attachment":[{"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/categories?post=91"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.minpx.com\/index.php\/wp-json\/wp\/v2\/tags?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}